{"id":349,"date":"2019-07-18T20:23:13","date_gmt":"2019-07-18T20:23:13","guid":{"rendered":"https:\/\/neusite.nahiro.net\/?page_id=349"},"modified":"2026-06-25T21:28:42","modified_gmt":"2026-06-25T19:28:42","slug":"terminos-y-condiciones","status":"publish","type":"page","link":"https:\/\/nahiro.net\/es\/terminos-y-condiciones\/","title":{"rendered":"Terminos y Condiciones"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"349\" class=\"elementor elementor-349\" data-elementor-settings=\"{&quot;element_pack_global_tooltip_width&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_width_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;element_pack_global_tooltip_padding&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_padding_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_tablet&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true},&quot;element_pack_global_tooltip_border_radius_mobile&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;top&quot;:&quot;&quot;,&quot;right&quot;:&quot;&quot;,&quot;bottom&quot;:&quot;&quot;,&quot;left&quot;:&quot;&quot;,&quot;isLinked&quot;:true}}\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b551b01 e-flex e-con-boxed e-con e-parent\" data-id=\"b551b01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-a13aae9 e-con-full e-flex e-con e-child\" data-id=\"a13aae9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67ad646 elementor-widget elementor-widget-heading\" data-id=\"67ad646\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Terminos y Condiciones<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8090bae e-flex e-con-boxed e-con e-parent\" data-id=\"8090bae\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e68f208 e-con-full e-flex e-con e-child\" data-id=\"e68f208\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c90b266 elementor-widget elementor-widget-text-editor\" data-id=\"c90b266\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nahiro.net en el \u00e1mbito de la creaci\u00f3n de sitios web (y software relacionado con el sitio web) y en el \u00e1mbito del mantenimiento, cuidado, reparaci\u00f3n y restauraci\u00f3n de sitios web (y software relacionado con el sitio web) con fecha del 27 de julio de 2018<\/p><p><strong>1 \u00c1mbito de aplicaci\u00f3n<\/strong><\/p><p>Para contratos con Nahiro.net (en adelante, Nahiro.net ) y sus socios contractuales (en adelante, clientes), se aplican exclusivamente estas condiciones generales de contrataci\u00f3n (CGC) presentes.<\/p><p>Los servicios ofrecidos por Nahiro.net est\u00e1n dirigidos a empresarios en el sentido del \u00a7 14 BGB, as\u00ed como a clientes privados.<\/p><p>En caso de que existan condiciones comerciales por parte del cliente, solo se aplicar\u00e1n aquellas disposiciones que coincidan en contenido (validez de congruencia). Las disposiciones contradictorias se eliminan sin reemplazo.<\/p><p>No se realizar\u00e1n acuerdos orales adicionales a este contrato. Todos los acuerdos requieren la forma escrita para su validez seg\u00fan el \u00a7 126 BGB.<\/p><p>Los acuerdos contractuales individuales tienen prioridad sobre estas CGC seg\u00fan el \u00a7 305b BGB.<\/p><p><strong>2 Servicios<\/strong><\/p><p>Nahiro.net ofrece en el \u00e1mbito de la creaci\u00f3n de sitios web los siguientes servicios:<\/p><p>Programaci\u00f3n de software personalizado dentro de un sistema de gesti\u00f3n de contenidos<br \/>Productos de base de datos,<br \/>Tiendas en l\u00ednea<br \/>Alojamiento web,<br \/>Programaci\u00f3n de APPS (IOS, Android, Windows)<br \/>Creaci\u00f3n de textos editoriales,<br \/>Medidas de marketing en l\u00ednea y fuera de l\u00ednea<br \/>Trabajos gr\u00e1ficos en el \u00e1rea de impresi\u00f3n y no impresi\u00f3n,<br \/>Nahiro.net ofrece en el \u00e1mbito del mantenimiento, cuidado, reparaci\u00f3n y restauraci\u00f3n de sitios web los siguientes servicios:<\/p><p>Mantenimiento de la operatividad del sitio web o software, especialmente mediante la actualizaci\u00f3n autom\u00e1tica regular realizada por Nahiro.net a una nueva versi\u00f3n del software utilizado (actualizaci\u00f3n), tan pronto como est\u00e9 disponible.<br \/>Reparaci\u00f3n debido a un mal funcionamiento o una solicitud del cliente en forma de eliminaci\u00f3n de defectos que impiden o hacen imposible el uso adecuado del sitio web o software. Esto tambi\u00e9n incluye las consecuencias de un manejo incorrecto.<br \/>La obligaci\u00f3n de rendimiento individual y concreta para las ofertas de Nahiro.net se deriva del concepto de rendimiento acordado con el cliente, que se convierte en una parte fundamental del contrato.<\/p><p><strong>3 Colaboraci\u00f3n y ejecuci\u00f3n<\/strong><\/p><p>Si el cliente desea incluir contenido individual en el producto, esto conlleva una obligaci\u00f3n de colaboraci\u00f3n por su parte.<\/p><p>En el \u00e1mbito de la creaci\u00f3n de sitios web, el cliente garantiza que los contenidos proporcionados por \u00e9l (especialmente textos, im\u00e1genes, v\u00eddeos, grabaciones de audio, etc.) no infringen derechos de terceros y pueden ser publicados en su nombre. Nahiro.net no asume ninguna responsabilidad por la publicaci\u00f3n de contenidos que infrinjan los derechos de terceros por las razones mencionadas anteriormente.<\/p><p>En el \u00e1mbito del mantenimiento, cuidado, reparaci\u00f3n y restauraci\u00f3n de sitios web, el cliente garantiza que informar\u00e1 a Nahiro.net de cualquier mal funcionamiento del sitio web o software inmediatamente despu\u00e9s de detectarlo. Adem\u00e1s, el cliente est\u00e1 obligado a colaborar en la medida razonable en la b\u00fasqueda y correcci\u00f3n de errores, especialmente si existen informes de defectos, protocolos de prueba, notificaciones de errores, etc., estos deben ser proporcionados inmediatamente a Nahiro.net.<\/p><p>La solicitud de soporte del socio contractual\/cliente se procesa priorizando seg\u00fan el orden de llegada y el tipo de soporte. Es irrelevante c\u00f3mo se presenta la solicitud de soporte al contratista.<\/p><p>No existe un derecho legal a la soluci\u00f3n de problemas dentro de un marco de tiempo especificado por el contratista.<\/p><p>Para resolver el problema, puede ser necesario que Nahiro.net contacte con los fabricantes de los productos. Debido a las diferentes zonas horarias, esto puede llevar a retrasos en el procesamiento de la solicitud de soporte.<\/p><p><strong>4 Aceptaci\u00f3n<\/strong><\/p><p>Para la finalizaci\u00f3n del trabajo contractualmente acordado en el \u00e1rea de creaci\u00f3n de sitios web, se requiere una aceptaci\u00f3n.<\/p><p>Los criterios de rendimiento acordados conjuntamente en el concepto contractual sirven como base para los criterios de aceptaci\u00f3n.<\/p><p>El cliente se compromete a realizar una aceptaci\u00f3n dentro de los 14 d\u00edas posteriores a la finalizaci\u00f3n del trabajo. Despu\u00e9s de este per\u00edodo, se considera que el trabajo ha sido aceptado.<\/p><p>La aceptaci\u00f3n no puede ser negada debido a defectos insignificantes.<\/p><p><strong>5 Derechos de autor y derechos de uso<\/strong><\/p><p>Todos los derechos de autor permanecen con el autor o los autores conjuntos de la obra seg\u00fan el \u00a7 29 UrhG.<\/p><p>Nahiro.net otorga al cliente un derecho simple de uso seg\u00fan el \u00a7 31 Abs. 3 UrhG. Este derecho permite al cliente utilizar la obra para los prop\u00f3sitos de uso mencionados en el concepto de rendimiento y teniendo en cuenta las restricciones de contenido, espaciales y temporales acordadas.<\/p><p>Este derecho de uso no permite al cliente realizar cambios independientes de importancia significativa en la obra. Adem\u00e1s, no permite al cliente otorgar derechos de uso adicionales a un tercero.<\/p><p>Nahiro.net tambi\u00e9n se reserva el derecho de continuar utilizando la obra o partes de la obra o de utilizar elementos fundamentales de la obra de otra manera.<\/p><p>Nahiro.net tiene el derecho de colocar una referencia a la autor\u00eda de la obra creada en un lugar adecuado en el sitio web. Esta referencia debe integrarse visualmente en el dise\u00f1o del sitio web y contiene informaci\u00f3n adicional sobre el nombre y una forma de contacto f\u00e1cil con el autor.<\/p><p><strong>6 Precios y condiciones de pago<\/strong><\/p><p>Todos los precios mencionados son precios netos. Las facturas son pagaderas inmediatamente a la cuenta bancaria mencionada en la factura o a trav\u00e9s de PayPal sin deducciones.<\/p><p>El 50% del monto de la factura debe pagarse como un pago inicial a la cuenta bancaria mencionada en la factura o a trav\u00e9s de PayPal sin deducciones, el saldo restante debe pagarse antes de la entrega de los datos\/servicios tambi\u00e9n a la cuenta bancaria mencionada en la factura o a trav\u00e9s de PayPal sin deducciones.<\/p><p><strong>7 Servicios adicionales<\/strong><\/p><p>Otros servicios adicionales, no incluidos en el concepto de rendimiento del contrato pero deseados por el cliente, deben ser pagados por separado.<\/p><p>La facturaci\u00f3n se realiza sobre la base de horas iniciadas.<\/p><p><strong>8 Garant\u00eda limitada, responsabilidad<\/strong><\/p><p>Si la instalaci\u00f3n de WordPress se actualiza por s\u00ed misma o por los socios contractuales, y\/o si se a\u00f1aden\/eliminan\/actualizan plugins despu\u00e9s de la finalizaci\u00f3n del proyecto; podr\u00eda haber una posibilidad de que algunas funciones no funcionen. Podemos repararlo m\u00e1s tarde para usted, pero estos escenarios de caso no nos har\u00edan responsables de ninguna p\u00e9rdida por parte del cliente\/socios contractuales. Nahiro.net no asume ninguna responsabilidad por el rendimiento o el funcionamiento adecuado de componentes de terceros, como plugins, temas o software, que se utilizaron para el desarrollo o la ejecuci\u00f3n del contrato.<\/p><p>El socio contractual\/cliente exonera a Nahiro.net de todas las reclamaciones, costos y gastos que puedan surgir y que se deriven directa o indirectamente del incumplimiento de cualquiera de sus obligaciones bajo este contrato por parte del socio contractual\/cliente, incluidas todas las reclamaciones que puedan alegar que los servicios prestados por Nahiro.net seg\u00fan esta propuesta de desarrollo violan una patente, derecho de autor, secreto comercial o un derecho similar de un tercero.<\/p><p>Nahiro.net no es responsable de los costos, da\u00f1os o lucro cesante debido al incumplimiento de los plazos acordados. Una vez que el proyecto\/contrato ha comenzado, no se aceptar\u00e1n m\u00e1s solicitudes de reembolso.<\/p><p>Nahiro.net no es responsable de los costos, da\u00f1os o lucro cesante que resulten de la no disponibilidad del sitio web, sus servidores, software o del material proporcionado por el socio contractual\/cliente.<\/p><p><strong>9 Referencias<\/strong><\/p><p>Nahiro.net tiene derecho, despu\u00e9s de prestar el servicio contractualmente acordado, a llevar p\u00fablicamente el nombre del cliente como referencia de cliente. Este derecho tambi\u00e9n incluye el uso de cualquier marca registrada (especialmente marcas de palabras y marcas de im\u00e1genes) del cliente para llevar en listas de referencias, que son p\u00fablicamente accesibles en el sitio web de Nahiro.net.<\/p><p><strong>10 Retiro y terminaci\u00f3n<\/strong><\/p><p>Para servicios en el \u00e1rea de creaci\u00f3n de sitios web, ambas partes acuerdan un derecho contractual de retiro bajo las siguientes condiciones:<\/p><p>Nahiro.net se otorga un derecho de retiro si el cliente no cumple con su obligaci\u00f3n de pago. Esto es especialmente el caso si un pago por adelantado acordado no se realiza o no se realiza a tiempo.<\/p><p>Para la omisi\u00f3n de acciones colaborativas en el \u00e1rea de creaci\u00f3n de sitios web seg\u00fan el \u00a7 3 Abs. 2 de estas CGC, que resulten en un retraso en la aceptaci\u00f3n, Nahiro.net tiene derecho a una compensaci\u00f3n adecuada seg\u00fan el \u00a7 642 Abs. 1 en conexi\u00f3n con el \u00a7 642 Abs. 2 BGB.<\/p><p>Nahiro.net tambi\u00e9n est\u00e1 autorizado para establecer un plazo razonable al cliente seg\u00fan el \u00a7 643 BGB para realizar la acci\u00f3n colaborativa y, si este plazo expira, para terminar el contrato.<\/p><p>Para servicios en el \u00e1rea de mantenimiento, cuidado, reparaci\u00f3n y restauraci\u00f3n de sitios web, se otorga a Nahiro.net un derecho de terminaci\u00f3n si el cliente no cumple con su obligaci\u00f3n de pago. Esto es especialmente el caso si el cliente no paga el monto de la factura al menos dos veces o no lo hace a tiempo.<\/p><p>El derecho mutuo de terminaci\u00f3n sin previo aviso por una causa justa no se ve afectado por esto. Una causa justa existe especialmente en aquellos incidentes que afectan negativamente la relaci\u00f3n de confianza entre el contratista y el cliente de manera significativa y hacen que la cooperaci\u00f3n continua hasta la terminaci\u00f3n ordinaria parezca irrazonable.<\/p><p><strong>11 Ley aplicable y jurisdicci\u00f3n<\/strong><\/p><p>Se aplica exclusivamente la ley de la Rep\u00fablica Federal de Alemania con la exclusi\u00f3n expl\u00edcita de la Ley de Ventas de la ONU.<\/p><p><strong>12 Disposiciones finales<\/strong><\/p><p>Nahiro.net est\u00e1 autorizado a cambiar estas CGC posteriormente. Las razones para posibles cambios son, entre otras, cambios en la ley, nueva jurisprudencia o condiciones del mercado que tengan efectos significativos en el modelo de negocio de Nahiro.net.<\/p><p>En caso de cambio de estas CGC, se informar\u00e1 al cliente sobre el cambio y tendr\u00e1 cuatro semanas desde el momento del acceso a la nueva versi\u00f3n para objetarla.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Terminos y Condiciones Nahiro.net en el \u00e1mbito de la creaci\u00f3n de sitios web (y software relacionado con el sitio web) y en el \u00e1mbito del mantenimiento, cuidado, reparaci\u00f3n y restauraci\u00f3n de sitios web (y software relacionado con el sitio web) con fecha del 27 de julio de 2018 1 \u00c1mbito de aplicaci\u00f3n Para contratos con [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-349","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/pages\/349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/comments?post=349"}],"version-history":[{"count":0,"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/pages\/349\/revisions"}],"wp:attachment":[{"href":"https:\/\/nahiro.net\/es\/wp-json\/wp\/v2\/media?parent=349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}